{"id":228,"count":4,"description":"","link":"https:\/\/loransmedical.com\/fr\/portfolio_group\/dental-fr\/","name":"Dental","slug":"dental-fr","taxonomy":"cpt_portfolio_group","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/loransmedical.com\/fr\/wp-json\/wp\/v2\/cpt_portfolio_group\/228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loransmedical.com\/fr\/wp-json\/wp\/v2\/cpt_portfolio_group"}],"about":[{"href":"https:\/\/loransmedical.com\/fr\/wp-json\/wp\/v2\/taxonomies\/cpt_portfolio_group"}],"wp:post_type":[{"href":"https:\/\/loransmedical.com\/fr\/wp-json\/wp\/v2\/cpt_portfolio?cpt_portfolio_group=228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}